{"id":7427,"date":"2015-10-08T10:14:39","date_gmt":"2015-10-08T08:14:39","guid":{"rendered":"http:\/\/rivedroite.ch\/en\/?page_id=7427"},"modified":"2022-02-24T21:05:38","modified_gmt":"2022-02-24T20:05:38","slug":"properties-for-sale","status":"publish","type":"page","link":"https:\/\/rivedroite.ch\/en\/properties-for-sale\/","title":{"rendered":"Properties for sale"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":2,"comment_status":"closed","ping_status":"closed","template":"page-templates\/property_list_half.php","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-7427","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Properties for sale in Geneva - Rive droite real estate<\/title>\n<meta name=\"description\" content=\"Consult our properties for sale in Geneva and the nearby Vaudois coast. Rive Droite Real Estate Specialist of the Geneva Right Bank.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rivedroite.ch\/en\/properties-for-sale\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Properties for sale in Geneva - Rive droite real estate\" \/>\n<meta property=\"og:description\" content=\"Consult our properties for sale in Geneva and the nearby Vaudois coast. Rive Droite Real Estate Specialist of the Geneva Right Bank.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rivedroite.ch\/en\/properties-for-sale\/\" \/>\n<meta property=\"og:site_name\" content=\"Rive droite immobilier\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-24T20:05:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/rivedroite.ch\/wp-content\/uploads\/2022\/02\/img-about-real-estate-agency-rive-droite-immobilier-courtage.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Properties for sale in Geneva - Rive droite real estate\" \/>\n<meta name=\"twitter:description\" content=\"Consult our properties for sale in Geneva and the nearby Vaudois coast. Rive Droite Real Estate Specialist of the Geneva Right Bank.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/rivedroite.ch\/wp-content\/uploads\/2022\/02\/img-about-real-estate-agency-rive-droite-immobilier-courtage.jpg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rivedroite.ch\\\/en\\\/properties-for-sale\\\/\",\"url\":\"https:\\\/\\\/rivedroite.ch\\\/en\\\/properties-for-sale\\\/\",\"name\":\"Properties for sale in Geneva - Rive droite real estate\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rivedroite.ch\\\/en\\\/#website\"},\"datePublished\":\"2015-10-08T08:14:39+00:00\",\"dateModified\":\"2022-02-24T20:05:38+00:00\",\"description\":\"Consult our properties for sale in Geneva and the nearby Vaudois coast. Rive Droite Real Estate Specialist of the Geneva Right Bank.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rivedroite.ch\\\/en\\\/properties-for-sale\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/rivedroite.ch\\\/en\\\/properties-for-sale\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rivedroite.ch\\\/en\\\/properties-for-sale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Homepage\",\"item\":\"https:\\\/\\\/rivedroite.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Properties for sale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rivedroite.ch\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/rivedroite.ch\\\/en\\\/\",\"name\":\"Rive droite immobilier\",\"description\":\"Geneva Real Estate Agency\",\"publisher\":{\"@id\":\"https:\\\/\\\/rivedroite.ch\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rivedroite.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/rivedroite.ch\\\/en\\\/#organization\",\"name\":\"Rive Droite Immobilier - Geneva real estate agency\",\"url\":\"https:\\\/\\\/rivedroite.ch\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/rivedroite.ch\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/rivedroite.ch\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/logo-rive-droite-immobilier@2X.png\",\"contentUrl\":\"https:\\\/\\\/rivedroite.ch\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/logo-rive-droite-immobilier@2X.png\",\"width\":500,\"height\":100,\"caption\":\"Rive Droite Immobilier - Geneva real estate agency\"},\"image\":{\"@id\":\"https:\\\/\\\/rivedroite.ch\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Properties for sale in Geneva - Rive droite real estate","description":"Consult our properties for sale in Geneva and the nearby Vaudois coast. Rive Droite Real Estate Specialist of the Geneva Right Bank.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rivedroite.ch\/en\/properties-for-sale\/","og_locale":"en_US","og_type":"article","og_title":"Properties for sale in Geneva - Rive droite real estate","og_description":"Consult our properties for sale in Geneva and the nearby Vaudois coast. Rive Droite Real Estate Specialist of the Geneva Right Bank.","og_url":"https:\/\/rivedroite.ch\/en\/properties-for-sale\/","og_site_name":"Rive droite immobilier","article_modified_time":"2022-02-24T20:05:38+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/rivedroite.ch\/wp-content\/uploads\/2022\/02\/img-about-real-estate-agency-rive-droite-immobilier-courtage.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Properties for sale in Geneva - Rive droite real estate","twitter_description":"Consult our properties for sale in Geneva and the nearby Vaudois coast. Rive Droite Real Estate Specialist of the Geneva Right Bank.","twitter_image":"https:\/\/rivedroite.ch\/wp-content\/uploads\/2022\/02\/img-about-real-estate-agency-rive-droite-immobilier-courtage.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/rivedroite.ch\/en\/properties-for-sale\/","url":"https:\/\/rivedroite.ch\/en\/properties-for-sale\/","name":"Properties for sale in Geneva - Rive droite real estate","isPartOf":{"@id":"https:\/\/rivedroite.ch\/en\/#website"},"datePublished":"2015-10-08T08:14:39+00:00","dateModified":"2022-02-24T20:05:38+00:00","description":"Consult our properties for sale in Geneva and the nearby Vaudois coast. Rive Droite Real Estate Specialist of the Geneva Right Bank.","breadcrumb":{"@id":"https:\/\/rivedroite.ch\/en\/properties-for-sale\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rivedroite.ch\/en\/properties-for-sale\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/rivedroite.ch\/en\/properties-for-sale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Homepage","item":"https:\/\/rivedroite.ch\/en\/"},{"@type":"ListItem","position":2,"name":"Properties for sale"}]},{"@type":"WebSite","@id":"https:\/\/rivedroite.ch\/en\/#website","url":"https:\/\/rivedroite.ch\/en\/","name":"Rive droite immobilier","description":"Geneva Real Estate Agency","publisher":{"@id":"https:\/\/rivedroite.ch\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rivedroite.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/rivedroite.ch\/en\/#organization","name":"Rive Droite Immobilier - Geneva real estate agency","url":"https:\/\/rivedroite.ch\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/rivedroite.ch\/en\/#\/schema\/logo\/image\/","url":"https:\/\/rivedroite.ch\/wp-content\/uploads\/2015\/09\/logo-rive-droite-immobilier@2X.png","contentUrl":"https:\/\/rivedroite.ch\/wp-content\/uploads\/2015\/09\/logo-rive-droite-immobilier@2X.png","width":500,"height":100,"caption":"Rive Droite Immobilier - Geneva real estate agency"},"image":{"@id":"https:\/\/rivedroite.ch\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/rivedroite.ch\/en\/wp-json\/wp\/v2\/pages\/7427","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rivedroite.ch\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/rivedroite.ch\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/rivedroite.ch\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rivedroite.ch\/en\/wp-json\/wp\/v2\/comments?post=7427"}],"version-history":[{"count":0,"href":"https:\/\/rivedroite.ch\/en\/wp-json\/wp\/v2\/pages\/7427\/revisions"}],"wp:attachment":[{"href":"https:\/\/rivedroite.ch\/en\/wp-json\/wp\/v2\/media?parent=7427"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}